{"id":1750,"date":"2021-04-09T15:47:17","date_gmt":"2021-04-09T15:47:17","guid":{"rendered":"https:\/\/www.bioleft.org\/?page_id=1750"},"modified":"2025-12-12T12:09:00","modified_gmt":"2025-12-12T15:09:00","slug":"equipo-y-redes","status":"publish","type":"page","link":"https:\/\/www.bioleft.org\/es\/equipo-y-redes\/","title":{"rendered":"Equipo y redes"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1750\" class=\"elementor elementor-1750\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4eabd20 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4eabd20\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-937c957\" data-id=\"937c957\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a92854e elementor-widget elementor-widget-text-editor\" data-id=\"a92854e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>Bioleft es una iniciativa de un equipo interdisciplinario de investigaci\u00f3n, conformado por personas especializadas en econom\u00eda, agronom\u00eda, ambiente, gen\u00e9tica, derecho y propiedad intelectual, producci\u00f3n e investigaci\u00f3n colaborativa y comunicaci\u00f3n. Trabajamos para incentivar el desarrollo de transformaciones m\u00e1s sostenibles, sustentables e inclusivas. El proyecto fue incubado en el <a href=\"http:\/\/www.fund-cenit.org.ar\/home\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.fund-cenit.org.ar\/home\/&amp;source=gmail&amp;ust=1538858402231000&amp;usg=AFQjCNGKKcoue8OJHo5iGIpOux2DVMNh_A\">Centro de Investigaciones para la Transformaci\u00f3n (CENIT)\u00a0<\/a>junto al\u00a0<a href=\"https:\/\/steps-centre.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/steps-centre.org\/&amp;source=gmail&amp;ust=1538858402231000&amp;usg=AFQjCNGNAPpvO2vAJmRYyHrpCbp7-LYY4w\">STEPS Centre<\/a>, en el marco del proyecto global\u00a0<a href=\"https:\/\/steps-centre.org\/project\/pathways-network\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/steps-centre.org\/project\/pathways-network\/&amp;source=gmail&amp;ust=1538858402231000&amp;usg=AFQjCNERs2-5evim0C2pCqikyi8AqExGGw\">Transformative pathways to sustainability<\/a>.<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8564603 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8564603\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-299eed4\" data-id=\"299eed4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ccce43 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0ccce43\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d3c5e elementor-widget elementor-widget-text-editor\" data-id=\"c6d3c5e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333300;\">DIRECTORA<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c006d6e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c006d6e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51de1bb\" data-id=\"51de1bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c6c699 elementor-widget elementor-widget-text-editor\" data-id=\"5c6c699\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Almendra Cremaschi<\/h1><p>Soy ingeniera agr\u00f3noma, graduada en la Universidad Nacional de La Plata (UNLP). Me interesan los temas vinculados al desarrollo rural y la agricultura familiar, as\u00ed como el trabajo multidisciplinario y las metodolog\u00edas participativas para abordar problemas complejos como la sustentabilidad. Me sum\u00e9 al equipo del proyecto \u201cPathways to sustainability\u201d, donde investigo sobre sustentabilidad en semillas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ff291be\" data-id=\"ff291be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1389fb6 elementor-widget elementor-widget-image\" data-id=\"1389fb6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-300x300.png\" class=\"attachment-medium size-medium wp-image-4055\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Almendra-Cremaschi-Bioleft.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-009f262 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"009f262\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1117bec\" data-id=\"1117bec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6db7d4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b6db7d4\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e48d308 elementor-widget elementor-widget-text-editor\" data-id=\"e48d308\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333300;\">EQUIPO<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9027884 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9027884\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f1f5b2\" data-id=\"8f1f5b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bce7ed4 elementor-widget elementor-widget-text-editor\" data-id=\"bce7ed4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Florencia Chena<\/h1><p>Soy licenciada en Administraci\u00f3n de Empresas (UNGS),\u00a0 coordinadora administrativa del Centro de Investigaciones para la Transformaci\u00f3n (CENIT-EEyN-UNSAM) de la Universidad Nacional de San Mart\u00edn. Estoy estudiando la especialidad en Gesti\u00f3n de la Tecnolog\u00eda y la Innovaci\u00f3n (UNSAM) y me interesa la gesti\u00f3n del cambio y el desarrollo tecnol\u00f3gico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b0378f0\" data-id=\"b0378f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea4585c elementor-widget elementor-widget-image\" data-id=\"ea4585c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-300x300.png\" class=\"attachment-medium size-medium wp-image-4057\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Florencia-Chena-Bioleft.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a700dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a700dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-072a57a\" data-id=\"072a57a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d053837 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d053837\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61c768d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61c768d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6302234\" data-id=\"6302234\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b4e7876 elementor-widget elementor-widget-text-editor\" data-id=\"b4e7876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Mar\u00eda Laura Bravo<\/h1><p>Soy ingeniera agr\u00f3noma, recibida en la Universidad Nacional de La Plata (UNLP), donde me desempe\u00f1o como docente de Mejoramiento Gen\u00e9tico y Socioeconom\u00eda. Trabajo en aspectos vinculados al abordaje del Desarrollo Rural: dirijo proyectos de Extensi\u00f3n Universitaria y coordino proyectos de investigaci\u00f3n aplicada con organizaciones de la agricultura familiar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-864e14a\" data-id=\"864e14a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0375706 elementor-widget elementor-widget-image\" data-id=\"0375706\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-300x300.png\" class=\"attachment-medium size-medium wp-image-4060\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Maria-Laura-Bravo-Bioleft.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0fe63f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fe63f2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9f813a\" data-id=\"b9f813a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7e8262 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a7e8262\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a71eb1a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a71eb1a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bb61fb\" data-id=\"8bb61fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-882acd4 elementor-widget elementor-widget-text-editor\" data-id=\"882acd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Gustavo Schrauf<\/h1><p>Soy i<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">ngeniero agr\u00f3nomo graduado de la Universidad Nacional de Rosario (UNR), magister en Mejoramiento Gen\u00e9tico Vegetal por INTA-UNR, y doctor en Ciencias Agropecuarias por la Facultad de Agronom\u00eda de la Universidad de Buenos Aires (FAUBA).<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">\u00a0En esta \u00faltima instituci\u00f3n me desempe\u00f1o como profesor titular de la C\u00e1tedra de Gen\u00e9tica y director del Criadero \u201cCultivos del Sur\u201d.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8cea571\" data-id=\"8cea571\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c3926f elementor-widget elementor-widget-image\" data-id=\"7c3926f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-300x300.png\" class=\"attachment-medium size-medium wp-image-4058\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Gustavo-Schrauf-Bioleft.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf6e9e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf6e9e9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b8a23f4\" data-id=\"b8a23f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-104cfa2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"104cfa2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-220145c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"220145c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-129e08b\" data-id=\"129e08b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ed616 elementor-widget elementor-widget-text-editor\" data-id=\"81ed616\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Enrico Cresta<\/h1><p>Soy productor org\u00e1nico en la zona de R\u00edo Cuarto, C\u00f3rdoba, presidente del grupo de Cambio Rural &#8220;Pampaorg\u00e1nica Norte&#8221; y miembro de la comisi\u00f3n directiva del Movimiento Argentino para la Producci\u00f3n Org\u00e1nica (MAPO).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-901dde0\" data-id=\"901dde0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cb6a87 elementor-widget elementor-widget-image\" data-id=\"2cb6a87\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-300x200.jpg\" class=\"attachment-medium size-medium wp-image-1933\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-300x200.jpg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-1024x683.jpg 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-768x512.jpg 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-1536x1024.jpg 1536w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-2048x1365.jpg 2048w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/05\/IMG_4861-16x12.jpg 16w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be8c197 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be8c197\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2a9edbb\" data-id=\"2a9edbb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d37991 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1d37991\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc11fdd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc11fdd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8fedd65\" data-id=\"8fedd65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0367888 elementor-widget elementor-widget-text-editor\" data-id=\"0367888\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Yael Tachdjian<\/h1><p>Soy emprendedora y amante de la agricultura y la educaci\u00f3n ambiental. Mi pasi\u00f3n por la naturaleza me llev\u00f3 a involucrarme en proyectos como promotora de ProHuerta Inta y como miembro del equipo de Educaci\u00f3n para la Sustentabilidad en la ONG Germinar. Ahora, como coordinadora ambiental en Jardines Maternales Di\u00e1logos, sigo compartiendo mi amor por las huertas y el medio ambiente, siempre buscando nuevas formas de aprendizaje y ense\u00f1anza.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58d16fa\" data-id=\"58d16fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdd12bc elementor-widget elementor-widget-image\" data-id=\"bdd12bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-300x300.png\" class=\"attachment-medium size-medium wp-image-4127\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/06\/Yael-Tachdjian.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77333d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77333d3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea43b19\" data-id=\"ea43b19\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ed56a7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9ed56a7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73a75e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73a75e4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a743ec4\" data-id=\"a743ec4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86dd24a elementor-widget elementor-widget-text-editor\" data-id=\"86dd24a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Alfredo Zeballos<\/h1><p>Soy Licenciado en Biotecnolog\u00eda por la Universidad Nacional del Litoral y Mag\u00edster en Gen\u00e9tica Vegetal por la Universidad Nacional de Rosario. A lo largo de mi carrera, he trabajado en instituciones p\u00fablicas y privadas, donde particip\u00e9 y lider\u00e9 proyectos de mejoramiento gen\u00e9tico de diversos cultivos, contribuyendo al desarrollo de variedades m\u00e1s productivas y adaptadas. Mi gran motivaci\u00f3n es impulsar una agricultura m\u00e1s sustentable y respetuosa con el medioambiente, promoviendo y desarrollando pr\u00e1cticas que beneficien y logren empoderar a quienes cultivan la tierra.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0c0e6a5\" data-id=\"0c0e6a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b9dad0 elementor-widget elementor-widget-image\" data-id=\"0b9dad0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-300x300.png\" class=\"attachment-medium size-medium wp-image-5076\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Alfredo-Zeballos.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5753894 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5753894\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d02f929\" data-id=\"d02f929\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb1ba95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb1ba95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-98dd496\" data-id=\"98dd496\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10ab4f2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"10ab4f2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0041b8 elementor-widget elementor-widget-text-editor\" data-id=\"e0041b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Luciano Ber\u00f3n<\/h1><p>Soy licenciado en Comunicaci\u00f3n recibido en la Universidad Nacional de General Sarmiento. Con formaci\u00f3n en comunicaci\u00f3n estrat\u00e9gica y medios, busco aportar creatividad, pensamiento cr\u00edtico y capacidad para generar mensajes claros y atractivos. Mi trayectoria profesional incluye trabajos en radio, podcasts y medios culturales. Apasionado por contar historias y siempre buscando que cada mensaje llegue de manera aut\u00e9ntica y cercana.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f830f10\" data-id=\"f830f10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbefe5c elementor-widget elementor-widget-image\" data-id=\"fbefe5c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-300x300.png\" class=\"attachment-medium size-medium wp-image-5077\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-1024x1024.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/10\/Luciano-Beron.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e592e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e592e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f4b6509\" data-id=\"f4b6509\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-603d694 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"603d694\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09a0f57 elementor-widget elementor-widget-text-editor\" data-id=\"09a0f57\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333300;\">AMIGXS DE BIOLEFT<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b2150d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b2150d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a1ca9a\" data-id=\"4a1ca9a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cb536d elementor-widget elementor-widget-text-editor\" data-id=\"7cb536d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Juli\u00e1n Asinsten<\/h1><p>Economista graduado en la UBA, Doctorando en Econom\u00eda de la Innovaci\u00f3n en la UNSAM. Trabaja en el Centro de Investigaciones para la Transformaci\u00f3n desde 2018 en diferentes proyectos de investigaci\u00f3n y consultor\u00eda en temas de innovaci\u00f3n, desarrollo y sustentabilidad en RRNN, y fue coordinador de Bioleft. Est\u00e1 interesado en el dise\u00f1o e implementaci\u00f3n de procesos de co-creaci\u00f3n y el pensamiento sist\u00e9mico para abordar problemas complejos. Curs\u00f3 la Maestr\u00eda en Estudios Literarios Latinoamericanos (UNTREF).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0759a46\" data-id=\"0759a46\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce132f6 elementor-widget elementor-widget-image\" data-id=\"ce132f6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit-300x300.png\" class=\"attachment-medium size-medium wp-image-5326\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit-768x768.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2025\/12\/Fotos-para-web-cenit.png 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a4c8c79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a4c8c79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-afa0c7f\" data-id=\"afa0c7f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fa87ec elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6fa87ec\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af483d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af483d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-da4b4de\" data-id=\"da4b4de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8278b7e elementor-widget elementor-widget-text-editor\" data-id=\"8278b7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Claudio Demo<\/h1><p>Soy productor agropecuario familiar. Gestiono una chacra peque\u00f1a altamente diversificada (con partes agroec\u00f3logicas) y tengo entre mis metas ser autosuficiente en semillas (en articulaci\u00f3n con colegas) y el mayor avance lo he hecho en la obtenci\u00f3n y recuperaci\u00f3n de semillas de ma\u00edz, como Chucul, Dorado, Albinco, Quarentin, Rocillo, etc. Adem\u00e1s trabajo como docente en la Universidad Nacional de R\u00edo Cuarto (UNRC) donde abordo tem\u00e1ticas sociales y productivas. De formaci\u00f3n soy ingeniero agr\u00f3nomo y mag\u00edster en Desarrollo Rural (en Chiapas).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06651ab\" data-id=\"06651ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d32aa3 elementor-widget elementor-widget-image\" data-id=\"9d32aa3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-300x199.jpeg\" class=\"attachment-medium size-medium wp-image-2551\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-300x199.jpeg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-1024x680.jpeg 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-768x510.jpeg 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-1536x1020.jpeg 1536w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-2048x1360.jpeg 2048w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/DSC_0793-18x12.jpeg 18w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c80477c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c80477c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c8ecc41\" data-id=\"c8ecc41\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-804edd0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"804edd0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-edc802b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"edc802b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f1698d3\" data-id=\"f1698d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a7bc197 elementor-widget elementor-widget-text-editor\" data-id=\"a7bc197\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Milton V\u00e9lez<\/h1><p>Simplemente trato de ser agri-cultor como forma para conectarme con la tierra y sus ritmos, el acto de realizar agri-cultura me brinda en ocasiones la oportunidad de ser un observador del maravilloso arquetipo capaz de manifestar la semilla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-38ce62d\" data-id=\"38ce62d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be85ba4 elementor-widget elementor-widget-image\" data-id=\"be85ba4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton-300x169.jpeg\" class=\"attachment-medium size-medium wp-image-2575\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton-300x169.jpeg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton-1024x576.jpeg 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton-768x432.jpeg 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton-18x10.jpeg 18w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/milton.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f99e293 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f99e293\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a912ab1\" data-id=\"a912ab1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d640250 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d640250\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dd883e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dd883e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0ad9ed2\" data-id=\"0ad9ed2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3db5a69 elementor-widget elementor-widget-text-editor\" data-id=\"3db5a69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Daniel Presello<\/h1>\nSoy fitomejorador de ma\u00edz, actualmente retirado. Desarroll\u00e9 mi carrera en INTA Pergamino y cre\u00f3 las variedades Candelaria INTA, Candelaria D\u00fao INTA, Anita INTA y Eusilia INTA. Me motiva colaborar con agricultores en el fitomejoramiento orientado a la obtenci\u00f3n de variedades de polinizaci\u00f3n abierta. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bdeb391\" data-id=\"bdeb391\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7b027 elementor-widget elementor-widget-image\" data-id=\"bc7b027\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"217\" height=\"233\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/descarga-1.jpeg\" class=\"attachment-medium size-medium wp-image-3778\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/descarga-1.jpeg 217w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/descarga-1-11x12.jpeg 11w\" sizes=\"(max-width: 217px) 100vw, 217px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9663182 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9663182\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-af4c252\" data-id=\"af4c252\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88c9276 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"88c9276\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-361670c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"361670c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bfed86b\" data-id=\"bfed86b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3bf6c5 elementor-widget elementor-widget-text-editor\" data-id=\"a3bf6c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Patrick van Zwanenberg<\/h1><p>Soy licenciado en Ciencias Medioambientales y doctor en Estudios de Pol\u00edtica Cient\u00edfica y Tecnol\u00f3gica. Combino herramientas de los estudios sociales de la ciencia y la tecnolog\u00eda y pol\u00edticas cient\u00edficas. Me interesan las pol\u00edticas del conocimiento, los problemas de regulaci\u00f3n de la tecnolog\u00eda y las transformaciones de los procesos de innovaci\u00f3n que pueden dar mayor respuesta a las necesidades y valores sociales. Tambi\u00e9n participo en la investigaci\u00f3n sobre innovaci\u00f3n y desarrollo sustentable en Am\u00e9rica Latina.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-24fe827\" data-id=\"24fe827\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d533e6a elementor-widget elementor-widget-image\" data-id=\"d533e6a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2-300x300.jpg\" class=\"attachment-medium size-medium wp-image-144\" alt=\"Patrick Van Zwanenberg\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2-300x300.jpg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2-500x500.jpg 500w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/08\/Patrick_Van_Zwanenberg2.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e5ae9e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e5ae9e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d268f57\" data-id=\"d268f57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3fc563 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a3fc563\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63df796 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63df796\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e223e52\" data-id=\"e223e52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db1f1cb elementor-widget elementor-widget-text-editor\" data-id=\"db1f1cb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Mariano Fressoli<\/h1><p>Soy soci\u00f3logo y doctor en Ciencias Sociales por la Universidad de Buenos Aires (UBA) y Master of Arts in Cultural Studies en Goldsmiths College, University of London. Me desempe\u00f1o como investigador adjunto en el Consejo Nacional de Investigaciones Cient\u00edficas y T\u00e9cnicas (CONICET) e investigador del Centro de Investigaciones para la Transformaci\u00f3n (CENIT).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0126d07\" data-id=\"0126d07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a216f8f elementor-widget elementor-widget-image\" data-id=\"a216f8f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"281\" height=\"249\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/mfre-ccc.jpeg\" class=\"attachment-medium size-medium wp-image-2544\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/mfre-ccc.jpeg 281w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/11\/mfre-ccc-14x12.jpeg 14w\" sizes=\"(max-width: 281px) 100vw, 281px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80e60d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80e60d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de22798\" data-id=\"de22798\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef502d6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ef502d6\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92527ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"92527ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a1bed6\" data-id=\"6a1bed6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e15ee23 elementor-widget elementor-widget-text-editor\" data-id=\"e15ee23\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Tamara Perelmuter<\/h1><p>Soy licenciada en Ciencia Pol\u00edtica de la Universidad de Buenos Aires (UBA), magister en Estudios Latinoamericanos por la Universidad Nacional de San Mart\u00edn (UNSAM) y doctora en Ciencias Sociales por la UBA. Soy investigadora del Instituto de Estudios sobre Am\u00e9rica Latina y el Caribe (<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">IEALC)<\/span><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-weight: var( --e-global-typography-text-font-weight );\">, coordinadora del Grupo de Estudios sobre Ecolog\u00eda Pol\u00edtica desde Am\u00e9rica Latina (GEEPAL), integrante del Grupo de Estudios Rurales y del Grupo de Estudios de los Movimientos Sociales de Am\u00e9rica Latina (GER-GEMSAL) del Instituto de Investigaciones Gino Germani, y docente de la Facultad de Ciencias Sociales de la UBA. Mis trabajos de investigaci\u00f3n se centran en analizar los procesos de cercamiento de las semillas con hincapi\u00e9 en las transformaciones de la propiedad intelectual a partir de la inserci\u00f3n de la biotecnolog\u00eda al agro, y los diversos activismos en defensa de las semillas.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6849c5c\" data-id=\"6849c5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ed4c12 elementor-widget elementor-widget-image\" data-id=\"1ed4c12\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/06\/Foto-e1623770361656.png\" class=\"attachment-medium size-medium wp-image-2157\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/06\/Foto-e1623770361656.png 225w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/06\/Foto-e1623770361656-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2021\/06\/Foto-e1623770361656-12x12.png 12w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1436e01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1436e01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3941944\" data-id=\"3941944\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3a402 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3e3a402\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edd5c5d elementor-widget elementor-widget-text-editor\" data-id=\"edd5c5d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333300;\">NUESTRA RED<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b5e8b51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b5e8b51\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-228dc80\" data-id=\"228dc80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d15d5cc elementor-widget elementor-widget-image\" data-id=\"d15d5cc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Minka-Semillera-Bioleft-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-4044\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Minka-Semillera-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Minka-Semillera-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Minka-Semillera-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Minka-Semillera-Bioleft.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44d25de elementor-widget elementor-widget-image\" data-id=\"44d25de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logoaabda-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1262\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logoaabda-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logoaabda-300x300.jpg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logoaabda-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logoaabda.jpg 480w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-ef501b0\" data-id=\"ef501b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e85ead elementor-widget elementor-widget-image\" data-id=\"7e85ead\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Vaca-Bonsai-Bioleft-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-4043\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Vaca-Bonsai-Bioleft-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Vaca-Bonsai-Bioleft-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Vaca-Bonsai-Bioleft-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2024\/03\/Vaca-Bonsai-Bioleft.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-739e8f7 elementor-widget elementor-widget-image\" data-id=\"739e8f7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/15-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-3925\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/15-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/15-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/15-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/15.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-56d4206\" data-id=\"56d4206\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48ca17b elementor-widget elementor-widget-image\" data-id=\"48ca17b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/logounsam.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-3770\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/logounsam.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/06\/logounsam-12x12.jpg 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e901c5 elementor-widget elementor-widget-image\" data-id=\"8e901c5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/07\/logoSteps-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-118\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/07\/logoSteps-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/07\/logoSteps-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2018\/07\/logoSteps.jpg 170w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd7085 elementor-widget elementor-widget-image\" data-id=\"7fd7085\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/17-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-3928\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/17-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/17-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/17-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/17.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-0d38370\" data-id=\"0d38370\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-15ed3b7 elementor-widget elementor-widget-image\" data-id=\"15ed3b7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_fauba-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1250\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_fauba-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_fauba-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_fauba.jpg 250w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd5b820 elementor-widget elementor-widget-image\" data-id=\"dd5b820\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/MAPO_LOGO-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-1258\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/MAPO_LOGO-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/MAPO_LOGO-80x80.png 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/MAPO_LOGO.png 224w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-823e19e elementor-widget elementor-widget-image\" data-id=\"823e19e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_constelaci\u00f3n-e1602798929917-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1265\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_constelaci\u00f3n-e1602798929917-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_constelaci\u00f3n-e1602798929917-80x80.jpg 80w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-1b13e1b\" data-id=\"1b13e1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e889ce2 elementor-widget elementor-widget-image\" data-id=\"e889ce2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/16-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-3927\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/16-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/16-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/16-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/16.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c87e943 elementor-widget elementor-widget-image\" data-id=\"c87e943\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_renama-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1251\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_renama-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_renama-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_renama.jpg 225w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-75107d5\" data-id=\"75107d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c729062 elementor-widget elementor-widget-image\" data-id=\"c729062\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-1261\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-150x150.jpg 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-300x300.jpg 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-1024x1024.jpg 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-768x768.jpg 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-80x80.jpg 80w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-500x500.jpg 500w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis-1000x1000.jpg 1000w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2020\/10\/logo_lancis.jpg 1400w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d60014 elementor-widget elementor-widget-image\" data-id=\"0d60014\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/14-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-3926\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/14-150x150.png 150w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/14-300x300.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/14-12x12.png 12w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/14.png 500w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-695f837 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"695f837\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee6c15b\" data-id=\"ee6c15b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1012eb2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1012eb2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c781967 elementor-widget elementor-widget-text-editor\" data-id=\"c781967\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #333300;\">NOS FINANCIA<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80c732b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80c732b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-296452f\" data-id=\"296452f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-64a552b\" data-id=\"64a552b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5d5f3b elementor-widget elementor-widget-image\" data-id=\"b5d5f3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cfhfoundation.grantsmanagement08.com\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-300x169.png\" class=\"attachment-medium size-medium wp-image-3905\" alt=\"\" srcset=\"https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-300x169.png 300w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-1024x576.png 1024w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-768x432.png 768w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-1536x864.png 1536w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3-18x10.png 18w, https:\/\/www.bioleft.org\/wp-content\/uploads\/2023\/10\/fotos-1-3.png 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7f128c1\" data-id=\"7f128c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bioleft es una iniciativa de un equipo interdisciplinario de investigaci\u00f3n, conformado por personas especializadas en econom\u00eda, agronom\u00eda, ambiente, gen\u00e9tica, derecho [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-full-width.php","meta":{"footnotes":""},"class_list":["post-1750","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/pages\/1750"}],"collection":[{"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/comments?post=1750"}],"version-history":[{"count":285,"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/pages\/1750\/revisions"}],"predecessor-version":[{"id":5329,"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/pages\/1750\/revisions\/5329"}],"wp:attachment":[{"href":"https:\/\/www.bioleft.org\/es\/wp-json\/wp\/v2\/media?parent=1750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}